{"id":1763,"date":"2019-02-07T10:09:57","date_gmt":"2019-02-07T09:09:57","guid":{"rendered":"http:\/\/medeeenfurie.com\/blog\/?p=1763"},"modified":"2020-10-13T18:32:03","modified_gmt":"2020-10-13T17:32:03","slug":"thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter","status":"publish","type":"post","link":"https:\/\/medeeenfurie.com\/blog\/2019\/02\/07\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\/","title":{"rendered":"Thomas Kinkade (1958 &#8211; 2012), peintre du \u00ab\u00a0Home, Sweet Home\u00a0\u00bb &#8211; Thomas Kinkade (1958 &#8211; 2012), \u00ab\u00a0Home, Sweet Home\u00a0\u00bb painter"},"content":{"rendered":"<h4>Si vous n&rsquo;avez jamais entendu parler de Thomas Kinkade en France, c&rsquo;est normal, ce peintre est le plus connu aux USA mais un des plus m\u00e9pris\u00e9s par les critiques d&rsquo;art. Pour quelles raisons? Trop kitsch, trop mi\u00e8vre, trop de succ\u00e8s aussi, trop riche&#8230;<\/h4>\n<h4>Mais, pour qui sait aller au del\u00e0 des pr\u00e9jug\u00e9s, on d\u00e9couvre une oeuvre sensible, bas\u00e9e sur des valeurs familiales, d&rsquo;amour et de g\u00e9n\u00e9rosit\u00e9. Ses travaux refl\u00e8tent en g\u00e9n\u00e9ral le concept du \u00ab\u00a0Home, Sweet Home\u00a0\u00bb, en fran\u00e7ais \u00ab\u00a0Le foyer chaleureux\u00a0\u00bb.<\/h4>\n<h4>Ses toiles repr\u00e9sentent une sorte de paradis perdu de l&rsquo;enfance : une maison \u00e0 la campagne, au milieu de la nature en \u00e9t\u00e9, avec partout des arbres et des fleurs&#8230; image d\u2019\u00c9pinal certes mais qui rappelle des souvenirs \u00e0 tout le\u00a0 monde.<\/h4>\n<p>&nbsp;<\/p>\n<h4>If you have never heard of Thomas Kinkade in France, this is normal, this painter is the best known in the US but one of the most despised by art critics.<br \/>\nFor what reasons? Too kitsch, too cutesy, too successful too, too rich&#8230;<\/h4>\n<h4>But for those who know how to go beyond prejudices, we discover a sensitive work, based on family values, love and generosity. His works generally reflect the concept of \u00ab\u00a0Home, Sweet Home\u00a0\u00bb, in French \u00ab\u00a0Le foyer chaleureux\u00a0\u00bb.<\/h4>\n<h4>His paintings represent a kind of lost paradise of childhood: a house in the countryside, in the middle of nature in summer, with trees and flowers everywhere &#8230; image of Epinal certainly but reminiscent of memories to all world.<\/h4>\n<p><a href=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade01.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1765\" src=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade01-1024x764.jpg\" alt=\"\" width=\"700\" height=\"522\" srcset=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade01-1024x764.jpg 1024w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade01-300x224.jpg 300w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade01-768x573.jpg 768w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade01.jpg 1400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<h4><a href=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade02.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1766\" src=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade02-1024x727.jpg\" alt=\"\" width=\"700\" height=\"497\" srcset=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade02-1024x727.jpg 1024w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade02-300x213.jpg 300w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade02-768x545.jpg 768w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade02.jpg 1400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/h4>\n<h4><a href=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade03.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1767\" src=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade03-1024x819.jpg\" alt=\"\" width=\"700\" height=\"560\" srcset=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade03-1024x819.jpg 1024w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade03-300x240.jpg 300w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade03-768x614.jpg 768w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade03.jpg 1400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/h4>\n<h4><a href=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade04.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1768\" src=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade04-1024x819.jpg\" alt=\"\" width=\"700\" height=\"560\" srcset=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade04-1024x819.jpg 1024w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade04-300x240.jpg 300w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade04-768x614.jpg 768w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade04.jpg 1400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/h4>\n<h4><a href=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade05.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1769\" src=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade05-1024x576.jpg\" alt=\"\" width=\"700\" height=\"394\" srcset=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade05-1024x576.jpg 1024w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade05-300x169.jpg 300w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade05-768x432.jpg 768w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade05.jpg 1400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/h4>\n<h4><a href=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade06.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1770\" src=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade06-1024x854.jpg\" alt=\"\" width=\"700\" height=\"584\" srcset=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade06-1024x854.jpg 1024w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade06-300x250.jpg 300w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade06-768x640.jpg 768w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade06.jpg 1400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/h4>\n<h4><a href=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade07.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1771\" src=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade07-1024x813.jpg\" alt=\"\" width=\"700\" height=\"556\" srcset=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade07-1024x813.jpg 1024w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade07-300x238.jpg 300w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade07-768x610.jpg 768w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade07.jpg 1400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/h4>\n<h4><a href=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade08.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1772\" src=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade08-1024x728.jpg\" alt=\"\" width=\"700\" height=\"497\" srcset=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade08-1024x728.jpg 1024w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade08-300x213.jpg 300w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade08-768x546.jpg 768w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade08.jpg 1400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/h4>\n<h4><a href=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade09.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1773\" src=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade09-1024x800.jpg\" alt=\"\" width=\"700\" height=\"547\" srcset=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade09-1024x800.jpg 1024w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade09-300x234.jpg 300w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade09-768x600.jpg 768w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade09.jpg 1400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/h4>\n<h4><a href=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade10.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1774\" src=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade10-1024x682.jpg\" alt=\"\" width=\"700\" height=\"466\" srcset=\"https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade10-1024x682.jpg 1024w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade10-300x200.jpg 300w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade10-768x512.jpg 768w, https:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade10.jpg 1400w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><\/h4>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si vous n&rsquo;avez jamais entendu parler de Thomas Kinkade en France, c&rsquo;est normal, ce peintre est le plus connu aux USA mais un des plus m\u00e9pris\u00e9s par les critiques d&rsquo;art. Pour quelles raisons? Trop kitsch, trop mi\u00e8vre, trop de succ\u00e8s aussi, trop riche&#8230; Mais, pour qui sait aller au del\u00e0&#8230;<\/p>\n<p class=\"continue-reading-button\"> <a class=\"continue-reading-link\" href=\"https:\/\/medeeenfurie.com\/blog\/2019\/02\/07\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\/\">Continuer \u00e0 lire<i class=\"crycon-right-dir\"><\/i><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[40],"class_list":["post-1763","post","type-post","status-publish","format-standard","hentry","category-paintings_peintures","tag-painting_peinture"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Thomas Kinkade (1958 - 2012), peintre du &quot;Home, Sweet Home&quot; - Thomas Kinkade (1958 - 2012), &quot;Home, Sweet Home&quot; painter<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medeeenfurie.com\/blog\/2019\/02\/07\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Thomas Kinkade (1958 - 2012), peintre du &quot;Home, Sweet Home&quot; - Thomas Kinkade (1958 - 2012), &quot;Home, Sweet Home&quot; painter\" \/>\n<meta property=\"og:description\" content=\"Si vous n&rsquo;avez jamais entendu parler de Thomas Kinkade en France, c&rsquo;est normal, ce peintre est le plus connu aux USA mais un des plus m\u00e9pris\u00e9s par les critiques d&rsquo;art. Pour quelles raisons? Trop kitsch, trop mi\u00e8vre, trop de succ\u00e8s aussi, trop riche&#8230; Mais, pour qui sait aller au del\u00e0... Continuer \u00e0 lire\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medeeenfurie.com\/blog\/2019\/02\/07\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-07T09:09:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-13T17:32:03+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade01-1024x764.jpg\" \/>\n<meta name=\"author\" content=\"David Yukio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"David Yukio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/medeeenfurie.com\\\/blog\\\/2019\\\/02\\\/07\\\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medeeenfurie.com\\\/blog\\\/2019\\\/02\\\/07\\\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\\\/\"},\"author\":{\"name\":\"David Yukio\",\"@id\":\"https:\\\/\\\/medeeenfurie.com\\\/blog\\\/#\\\/schema\\\/person\\\/ef6dda9428a3da22a299c22d2f2f7229\"},\"headline\":\"Thomas Kinkade (1958 &#8211; 2012), peintre du \u00ab\u00a0Home, Sweet Home\u00a0\u00bb &#8211; Thomas Kinkade (1958 &#8211; 2012), \u00ab\u00a0Home, Sweet Home\u00a0\u00bb painter\",\"datePublished\":\"2019-02-07T09:09:57+00:00\",\"dateModified\":\"2020-10-13T17:32:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/medeeenfurie.com\\\/blog\\\/2019\\\/02\\\/07\\\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\\\/\"},\"wordCount\":275,\"publisher\":{\"@id\":\"https:\\\/\\\/medeeenfurie.com\\\/blog\\\/#\\\/schema\\\/person\\\/ef6dda9428a3da22a299c22d2f2f7229\"},\"image\":{\"@id\":\"https:\\\/\\\/medeeenfurie.com\\\/blog\\\/2019\\\/02\\\/07\\\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/medeeenfurie.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/OVH-Peinture-Thomas-Kinkade01-1024x764.jpg\",\"keywords\":[\"Painting_Peinture\"],\"articleSection\":[\"Paintings_Peintures\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/medeeenfurie.com\\\/blog\\\/2019\\\/02\\\/07\\\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\\\/\",\"url\":\"https:\\\/\\\/medeeenfurie.com\\\/blog\\\/2019\\\/02\\\/07\\\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\\\/\",\"name\":\"Thomas Kinkade (1958 - 2012), peintre du \\\"Home, Sweet Home\\\" - Thomas Kinkade (1958 - 2012), \\\"Home, Sweet Home\\\" painter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medeeenfurie.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/medeeenfurie.com\\\/blog\\\/2019\\\/02\\\/07\\\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/medeeenfurie.com\\\/blog\\\/2019\\\/02\\\/07\\\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/medeeenfurie.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/OVH-Peinture-Thomas-Kinkade01-1024x764.jpg\",\"datePublished\":\"2019-02-07T09:09:57+00:00\",\"dateModified\":\"2020-10-13T17:32:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medeeenfurie.com\\\/blog\\\/2019\\\/02\\\/07\\\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/medeeenfurie.com\\\/blog\\\/2019\\\/02\\\/07\\\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/medeeenfurie.com\\\/blog\\\/2019\\\/02\\\/07\\\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\\\/#primaryimage\",\"url\":\"http:\\\/\\\/medeeenfurie.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/OVH-Peinture-Thomas-Kinkade01-1024x764.jpg\",\"contentUrl\":\"http:\\\/\\\/medeeenfurie.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/OVH-Peinture-Thomas-Kinkade01-1024x764.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medeeenfurie.com\\\/blog\\\/2019\\\/02\\\/07\\\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/medeeenfurie.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Thomas Kinkade (1958 &#8211; 2012), peintre du \u00ab\u00a0Home, Sweet Home\u00a0\u00bb &#8211; Thomas Kinkade (1958 &#8211; 2012), \u00ab\u00a0Home, Sweet Home\u00a0\u00bb painter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medeeenfurie.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/medeeenfurie.com\\\/blog\\\/\",\"name\":\"M\u00e9d\u00e9e en Furie\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/medeeenfurie.com\\\/blog\\\/#\\\/schema\\\/person\\\/ef6dda9428a3da22a299c22d2f2f7229\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medeeenfurie.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/medeeenfurie.com\\\/blog\\\/#\\\/schema\\\/person\\\/ef6dda9428a3da22a299c22d2f2f7229\",\"name\":\"David Yukio\",\"logo\":{\"@id\":\"https:\\\/\\\/medeeenfurie.com\\\/blog\\\/#\\\/schema\\\/person\\\/image\\\/\"},\"url\":\"https:\\\/\\\/medeeenfurie.com\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Thomas Kinkade (1958 - 2012), peintre du \"Home, Sweet Home\" - Thomas Kinkade (1958 - 2012), \"Home, Sweet Home\" painter","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medeeenfurie.com\/blog\/2019\/02\/07\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\/","og_locale":"fr_FR","og_type":"article","og_title":"Thomas Kinkade (1958 - 2012), peintre du \"Home, Sweet Home\" - Thomas Kinkade (1958 - 2012), \"Home, Sweet Home\" painter","og_description":"Si vous n&rsquo;avez jamais entendu parler de Thomas Kinkade en France, c&rsquo;est normal, ce peintre est le plus connu aux USA mais un des plus m\u00e9pris\u00e9s par les critiques d&rsquo;art. Pour quelles raisons? Trop kitsch, trop mi\u00e8vre, trop de succ\u00e8s aussi, trop riche&#8230; Mais, pour qui sait aller au del\u00e0... Continuer \u00e0 lire","og_url":"https:\/\/medeeenfurie.com\/blog\/2019\/02\/07\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\/","article_published_time":"2019-02-07T09:09:57+00:00","article_modified_time":"2020-10-13T17:32:03+00:00","og_image":[{"url":"http:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade01-1024x764.jpg","type":"","width":"","height":""}],"author":"David Yukio","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"David Yukio","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/medeeenfurie.com\/blog\/2019\/02\/07\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\/#article","isPartOf":{"@id":"https:\/\/medeeenfurie.com\/blog\/2019\/02\/07\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\/"},"author":{"name":"David Yukio","@id":"https:\/\/medeeenfurie.com\/blog\/#\/schema\/person\/ef6dda9428a3da22a299c22d2f2f7229"},"headline":"Thomas Kinkade (1958 &#8211; 2012), peintre du \u00ab\u00a0Home, Sweet Home\u00a0\u00bb &#8211; Thomas Kinkade (1958 &#8211; 2012), \u00ab\u00a0Home, Sweet Home\u00a0\u00bb painter","datePublished":"2019-02-07T09:09:57+00:00","dateModified":"2020-10-13T17:32:03+00:00","mainEntityOfPage":{"@id":"https:\/\/medeeenfurie.com\/blog\/2019\/02\/07\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\/"},"wordCount":275,"publisher":{"@id":"https:\/\/medeeenfurie.com\/blog\/#\/schema\/person\/ef6dda9428a3da22a299c22d2f2f7229"},"image":{"@id":"https:\/\/medeeenfurie.com\/blog\/2019\/02\/07\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\/#primaryimage"},"thumbnailUrl":"http:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade01-1024x764.jpg","keywords":["Painting_Peinture"],"articleSection":["Paintings_Peintures"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/medeeenfurie.com\/blog\/2019\/02\/07\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\/","url":"https:\/\/medeeenfurie.com\/blog\/2019\/02\/07\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\/","name":"Thomas Kinkade (1958 - 2012), peintre du \"Home, Sweet Home\" - Thomas Kinkade (1958 - 2012), \"Home, Sweet Home\" painter","isPartOf":{"@id":"https:\/\/medeeenfurie.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/medeeenfurie.com\/blog\/2019\/02\/07\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\/#primaryimage"},"image":{"@id":"https:\/\/medeeenfurie.com\/blog\/2019\/02\/07\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\/#primaryimage"},"thumbnailUrl":"http:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade01-1024x764.jpg","datePublished":"2019-02-07T09:09:57+00:00","dateModified":"2020-10-13T17:32:03+00:00","breadcrumb":{"@id":"https:\/\/medeeenfurie.com\/blog\/2019\/02\/07\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/medeeenfurie.com\/blog\/2019\/02\/07\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/medeeenfurie.com\/blog\/2019\/02\/07\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\/#primaryimage","url":"http:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade01-1024x764.jpg","contentUrl":"http:\/\/medeeenfurie.com\/blog\/wp-content\/uploads\/2019\/02\/OVH-Peinture-Thomas-Kinkade01-1024x764.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/medeeenfurie.com\/blog\/2019\/02\/07\/thomas-kinkade-1958-2012-peintre-du-home-sweet-home-thomas-kinkade-1958-2012-home-sweet-home-painter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/medeeenfurie.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Thomas Kinkade (1958 &#8211; 2012), peintre du \u00ab\u00a0Home, Sweet Home\u00a0\u00bb &#8211; Thomas Kinkade (1958 &#8211; 2012), \u00ab\u00a0Home, Sweet Home\u00a0\u00bb painter"}]},{"@type":"WebSite","@id":"https:\/\/medeeenfurie.com\/blog\/#website","url":"https:\/\/medeeenfurie.com\/blog\/","name":"M\u00e9d\u00e9e en Furie","description":"","publisher":{"@id":"https:\/\/medeeenfurie.com\/blog\/#\/schema\/person\/ef6dda9428a3da22a299c22d2f2f7229"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medeeenfurie.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/medeeenfurie.com\/blog\/#\/schema\/person\/ef6dda9428a3da22a299c22d2f2f7229","name":"David Yukio","logo":{"@id":"https:\/\/medeeenfurie.com\/blog\/#\/schema\/person\/image\/"},"url":"https:\/\/medeeenfurie.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/medeeenfurie.com\/blog\/wp-json\/wp\/v2\/posts\/1763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medeeenfurie.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medeeenfurie.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medeeenfurie.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/medeeenfurie.com\/blog\/wp-json\/wp\/v2\/comments?post=1763"}],"version-history":[{"count":14,"href":"https:\/\/medeeenfurie.com\/blog\/wp-json\/wp\/v2\/posts\/1763\/revisions"}],"predecessor-version":[{"id":1804,"href":"https:\/\/medeeenfurie.com\/blog\/wp-json\/wp\/v2\/posts\/1763\/revisions\/1804"}],"wp:attachment":[{"href":"https:\/\/medeeenfurie.com\/blog\/wp-json\/wp\/v2\/media?parent=1763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medeeenfurie.com\/blog\/wp-json\/wp\/v2\/categories?post=1763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medeeenfurie.com\/blog\/wp-json\/wp\/v2\/tags?post=1763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}